{"id":20273,"date":"2014-07-07T14:26:05","date_gmt":"2014-07-07T14:26:05","guid":{"rendered":"http:\/\/demo.select-themes.com\/stockholm8\/?page_id=20273"},"modified":"2019-08-01T11:28:41","modified_gmt":"2019-08-01T09:28:41","slug":"progettazione-giardini","status":"publish","type":"page","link":"http:\/\/www.frullani.com\/en_US\/progettazione-giardini\/","title":{"rendered":"Design"},"content":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/1&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">A landscape design process could be defined as a sequence of analytical and creative steps, used by the landscape architect to develop the best project solution (both from a functional and aesthetic point of view), in relation to the location&#8217;s and to the client&#8217;s needs.<\/p>\n<p style=\"text-align: justify;\">The landscape architect Davide Giorgi (author of the book <a href=\"http:\/\/www.darioflaccovio.it\/libro.php\/il-giardino-df8555_C582\" target=\"_blank\">Il giardino &#8211; manuale di progettazione<\/a>) is at complete disposal of the customer to design green areas, perfect blend of originality and comfort, embellishing the whole picture with luxurious details, capable of making the garden unique and unexampled.<\/p>\n<p style=\"text-align: center;\"><strong>Frullani Group designs exclusively tailored gardens, just like a high fashion studio.<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][vc_empty_space height=&#8221;32px&#8221;]<a href=\"http:\/\/www.frullani.com\/it_IT\/realizzazione-giardini\/\" target=\"_self\"  class=\"qbutton  big_large_full_width\" style=\"\">Portfolio<\/a>[vc_empty_space height=&#8221;32px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/1&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">A landscape design process could be defined as a sequence of analytical and creative steps, used by the landscape architect to develop the best project solution (both fr&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Progettiamo giardini di lusso e design - Frullani Group Luxury Gardens<\/title>\n<meta name=\"description\" content=\"Grazie al paesaggista Davide Giorgi ideiamo giardini e piscine che siano una perfetta sintesi tra originalit\u00e0 e comfort. [Rendering di ogni progetto]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.frullani.com\/progettazione-giardini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progettiamo giardini di lusso e design - Frullani Group Luxury Gardens\" \/>\n<meta property=\"og:description\" content=\"Grazie al paesaggista Davide Giorgi ideiamo giardini e piscine che siano una perfetta sintesi tra originalit\u00e0 e comfort. [Rendering di ogni progetto]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.frullani.com\/progettazione-giardini\/\" \/>\n<meta property=\"og:site_name\" content=\"Frullani Group\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-01T09:28:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.frullani.com\/progettazione-giardini\/\",\"url\":\"http:\/\/www.frullani.com\/progettazione-giardini\/\",\"name\":\"Progettiamo giardini di lusso e design - Frullani Group Luxury Gardens\",\"isPartOf\":{\"@id\":\"http:\/\/www.frullani.com\/#website\"},\"datePublished\":\"2014-07-07T14:26:05+00:00\",\"dateModified\":\"2019-08-01T09:28:41+00:00\",\"description\":\"Grazie al paesaggista Davide Giorgi ideiamo giardini e piscine che siano una perfetta sintesi tra originalit\u00e0 e comfort. [Rendering di ogni progetto]\",\"breadcrumb\":{\"@id\":\"http:\/\/www.frullani.com\/progettazione-giardini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.frullani.com\/progettazione-giardini\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.frullani.com\/progettazione-giardini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.frullani.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progettazione giardini\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.frullani.com\/#website\",\"url\":\"http:\/\/www.frullani.com\/\",\"name\":\"Frullani Group\",\"description\":\"Crafting Outdoor Experiences\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.frullani.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progettiamo giardini di lusso e design - Frullani Group Luxury Gardens","description":"Grazie al paesaggista Davide Giorgi ideiamo giardini e piscine che siano una perfetta sintesi tra originalit\u00e0 e comfort. [Rendering di ogni progetto]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.frullani.com\/progettazione-giardini\/","og_locale":"it_IT","og_type":"article","og_title":"Progettiamo giardini di lusso e design - Frullani Group Luxury Gardens","og_description":"Grazie al paesaggista Davide Giorgi ideiamo giardini e piscine che siano una perfetta sintesi tra originalit\u00e0 e comfort. [Rendering di ogni progetto]","og_url":"http:\/\/www.frullani.com\/progettazione-giardini\/","og_site_name":"Frullani Group","article_modified_time":"2019-08-01T09:28:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.frullani.com\/progettazione-giardini\/","url":"http:\/\/www.frullani.com\/progettazione-giardini\/","name":"Progettiamo giardini di lusso e design - Frullani Group Luxury Gardens","isPartOf":{"@id":"http:\/\/www.frullani.com\/#website"},"datePublished":"2014-07-07T14:26:05+00:00","dateModified":"2019-08-01T09:28:41+00:00","description":"Grazie al paesaggista Davide Giorgi ideiamo giardini e piscine che siano una perfetta sintesi tra originalit\u00e0 e comfort. [Rendering di ogni progetto]","breadcrumb":{"@id":"http:\/\/www.frullani.com\/progettazione-giardini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.frullani.com\/progettazione-giardini\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.frullani.com\/progettazione-giardini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.frullani.com\/"},{"@type":"ListItem","position":2,"name":"Progettazione giardini"}]},{"@type":"WebSite","@id":"http:\/\/www.frullani.com\/#website","url":"http:\/\/www.frullani.com\/","name":"Frullani Group","description":"Crafting Outdoor Experiences","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.frullani.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/pages\/20273"}],"collection":[{"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/comments?post=20273"}],"version-history":[{"count":72,"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/pages\/20273\/revisions"}],"predecessor-version":[{"id":22930,"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/pages\/20273\/revisions\/22930"}],"wp:attachment":[{"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/media?parent=20273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}