{"id":22500,"date":"2017-02-06T10:26:47","date_gmt":"2017-02-06T09:26:47","guid":{"rendered":"http:\/\/www.frullani.com\/?page_id=22500"},"modified":"2017-02-20T09:13:57","modified_gmt":"2017-02-20T08:13:57","slug":"accademia-formativa-realizzare-giardini-piscine","status":"publish","type":"page","link":"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/","title":{"rendered":"Accademia formativa"},"content":{"rendered":"<p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column][vc_separator type=&#8221;full_width&#8221; border_style=&#8221;&#8221;][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Scegli la figura professionale che desideri diventare e noi ti formeremo gratuitamente<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Siamo una societ\u00e0 attiva nel centro italia da pi\u00f9 di 20 anni e in fase di espansione, per questo siamo alla <strong>ricerca di varie figure professionali<\/strong> sia esperti del settore sia giovani con poca o senza esperienza in qualsiasi parte d&#8217;Italia.<\/p>\n<p style=\"text-align: center;\"><strong>I candidati ideali sono di due tipi:<\/strong><\/p>\n<p style=\"text-align: center;\">Esperti di comprovata esperienza<\/p>\n<p style=\"text-align: center;\">oppure<\/p>\n<p style=\"text-align: center;\">Giovani disposti a seguire un percorso di formazione gratuita<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;22501&#8243; img_size=&#8221;300&#215;150&#8243; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">Vuoi diventare un <strong>commerciale Frullani?<\/strong><\/h3>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Cerchiamo commerciali\u00a0in qualsiasi parte d&#8217;Italia, offriamo un percorso di formazione e percentuali sul venduto stimolanti<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;22278&#8243; img_size=&#8221;300&#215;150&#8243; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">Desideri\u00a0imparare a <strong>costruire piscine<\/strong> da sogno?<\/h3>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Siamo alla ricerca di\u00a0persone con forte senso pratico capaci di gestire\u00a0vari lavoratori e operai con competenze diverse<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;22051&#8243; img_size=&#8221;300&#215;150&#8243; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">Vuoi\u00a0diventare un <strong>tecnico esperto<\/strong> nella realizzazione di giardini?<\/h3>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Cerchiamo un diplomato\/laureato in agraria o facolt\u00e0 simili con il desiderio\u00a0di specializzarti nella realizzazione di giardini<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;22502&#8243; img_size=&#8221;300&#215;150&#8243; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">Ti piacerebbe arrivare a <strong>gestire un nostro distaccamento<\/strong> aziendale?<\/h3>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Con il tempo e la formazione adeguata miriamo a far diventare, chi lo desidera, un vero e proprio distaccamento aziendale Frullani<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column][vc_empty_space height=&#8221;30px&#8221;][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">Scrivici i tuoi dati e ti ricontatteremo al pi\u00f9 presto<\/h3>\n<p>[\/vc_column_text]<div class=\"wpcf7 no-js\" id=\"wpcf7-f22430-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en_US\/wp-json\/wp\/v2\/pages\/22500#wpcf7-f22430-o1\" method=\"post\" class=\"wpcf7-form init default\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"22430\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f22430-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p>Il tuo nome (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>La tua email (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p>Il tuo numero di telefono (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-992\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-992\" \/><\/span>\n<\/p>\n<p>Il tuo messaggio\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control has-spinner wpcf7-submit landingSending\" type=\"submit\" value=\"Invia\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>[vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column][vc_separator type=&#8221;full_width&#8221; border_style=&#8221;&#8221;][vc_column_text] Scegli la figura professionale che desideri diventare e noi ti formeremo gratuitamente [\/vc_column_text][vc_empty_space][vc_column_text] Siamo una societ\u00e0 attiva nel centro italia da pi\u00f9 di 20 anni e in fase di espansione, per questo siamo alla ricerca di varie&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Accademia formativa - Frullani Group<\/title>\n<meta name=\"description\" content=\"Vuoi diventare un giardiniere o gestire la realizzazione di piscine di lusso? Noi ti offriamo la formazione per farlo, tu mettici la passione!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accademia formativa - Frullani Group\" \/>\n<meta property=\"og:description\" content=\"Vuoi diventare un giardiniere o gestire la realizzazione di piscine di lusso? Noi ti offriamo la formazione per farlo, tu mettici la passione!\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/\" \/>\n<meta property=\"og:site_name\" content=\"Frullani Group\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-20T08:13:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/\",\"url\":\"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/\",\"name\":\"Accademia formativa - Frullani Group\",\"isPartOf\":{\"@id\":\"http:\/\/www.frullani.com\/#website\"},\"datePublished\":\"2017-02-06T09:26:47+00:00\",\"dateModified\":\"2017-02-20T08:13:57+00:00\",\"description\":\"Vuoi diventare un giardiniere o gestire la realizzazione di piscine di lusso? Noi ti offriamo la formazione per farlo, tu mettici la passione!\",\"breadcrumb\":{\"@id\":\"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.frullani.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accademia formativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.frullani.com\/#website\",\"url\":\"http:\/\/www.frullani.com\/\",\"name\":\"Frullani Group\",\"description\":\"Crafting Outdoor Experiences\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.frullani.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accademia formativa - Frullani Group","description":"Vuoi diventare un giardiniere o gestire la realizzazione di piscine di lusso? Noi ti offriamo la formazione per farlo, tu mettici la passione!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/","og_locale":"it_IT","og_type":"article","og_title":"Accademia formativa - Frullani Group","og_description":"Vuoi diventare un giardiniere o gestire la realizzazione di piscine di lusso? Noi ti offriamo la formazione per farlo, tu mettici la passione!","og_url":"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/","og_site_name":"Frullani Group","article_modified_time":"2017-02-20T08:13:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/","url":"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/","name":"Accademia formativa - Frullani Group","isPartOf":{"@id":"http:\/\/www.frullani.com\/#website"},"datePublished":"2017-02-06T09:26:47+00:00","dateModified":"2017-02-20T08:13:57+00:00","description":"Vuoi diventare un giardiniere o gestire la realizzazione di piscine di lusso? Noi ti offriamo la formazione per farlo, tu mettici la passione!","breadcrumb":{"@id":"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.frullani.com\/en_US\/accademia-formativa-realizzare-giardini-piscine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.frullani.com\/"},{"@type":"ListItem","position":2,"name":"Accademia formativa"}]},{"@type":"WebSite","@id":"http:\/\/www.frullani.com\/#website","url":"http:\/\/www.frullani.com\/","name":"Frullani Group","description":"Crafting Outdoor Experiences","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.frullani.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/pages\/22500"}],"collection":[{"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/comments?post=22500"}],"version-history":[{"count":23,"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/pages\/22500\/revisions"}],"predecessor-version":[{"id":22551,"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/pages\/22500\/revisions\/22551"}],"wp:attachment":[{"href":"http:\/\/www.frullani.com\/en_US\/wp-json\/wp\/v2\/media?parent=22500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}